{"id":142368,"date":"2026-02-17T18:53:33","date_gmt":"2026-02-17T17:53:33","guid":{"rendered":"https:\/\/www.retaildetail.be\/?p=142368"},"modified":"2026-02-18T09:35:40","modified_gmt":"2026-02-18T08:35:40","slug":"carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/","title":{"rendered":"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Carrefour <\/strong>cl\u00f4ture l&rsquo;ann\u00e9e 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe fran\u00e7ais a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d&rsquo;affaires, mais a subi l&rsquo;impact des taux de change et des co\u00fbts d&rsquo;int\u00e9gration. Le PDG Alexandre Bompard affiche toutefois sa confiance et promet un nouveau plan radical.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Croissance malgr\u00e9 la contraction<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">2025 a \u00e9t\u00e9 une ann\u00e9e solide, avec une nette am\u00e9lioration notamment en France et en Espagne, selon Bompard. Le chiffre d&rsquo;affaires net a augment\u00e9 de 2,8 % pour atteindre 82,1 milliards d&rsquo;euros. Le r\u00e9sultat op\u00e9rationnel r\u00e9current (ROI) a toutefois l\u00e9g\u00e8rement baiss\u00e9 \u00e0 2,16 milliards d&rsquo;euros, contre 2,28 milliards d&rsquo;euros un an plus t\u00f4t.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le r\u00e9sultat net a m\u00eame fortement baiss\u00e9, passant de 723 millions d&rsquo;euros \u00e0 319 millions d&rsquo;euros. Carrefour attribue cette baisse principalement aux changements radicaux mis en \u0153uvre par le groupe : outre l&rsquo;int\u00e9gration de Cora et Match en France, le distributeur a vendu ses activit\u00e9s italiennes et a rachet\u00e9 la totalit\u00e9 du groupe Carrefour Br\u00e9sil.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La France se redresse, l&rsquo;Espagne tire l&rsquo;Europe<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En France (qui repr\u00e9sente encore 52 % du chiffre d&rsquo;affaires du groupe), le r\u00e9sultat op\u00e9rationnel r\u00e9current hors Cora et Match a augment\u00e9 de 11,3 % pour atteindre 1,10 milliard d&rsquo;euros, soit une marge op\u00e9rationnelle de 3 %. L&rsquo;int\u00e9gration de Cora et Match a co\u00fbt\u00e9 120 millions d&rsquo;euros, mais selon Bompard, elle est d\u00e9sormais achev\u00e9e avec succ\u00e8s : les premi\u00e8res synergies de co\u00fbts seraient d\u00e9j\u00e0 une r\u00e9alit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hors France, l&rsquo;Europe a enregistr\u00e9 un r\u00e9sultat d&rsquo;exploitation de 481 millions d&rsquo;euros, en hausse de 3,7 %. Le chiffre d&rsquo;affaires comparable a augment\u00e9 de 1,2 %. L&rsquo;Espagne a particuli\u00e8rement bien perform\u00e9 : son chiffre d&rsquo;affaires a progress\u00e9 de 1,9 % et son r\u00e9sultat d&rsquo;exploitation a grimp\u00e9 de 13,5 % pour atteindre 463 millions d&rsquo;euros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Carrefour souhaite d\u00e9sormais se concentrer sur trois pays coeur \u00e0 l&rsquo;international : la France, l&rsquo;Espagne et le Br\u00e9sil. Apr\u00e8s la vente de ses activit\u00e9s en Italie, <a href=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-vend-ses-activites-roumaines-a-paval-holding\/\">des n\u00e9gociations exclusives ont d\u00e9j\u00e0 \u00e9t\u00e9 entam\u00e9es en Roumanie<\/a> avec Paval Holding. Mercredi, Bompard pr\u00e9sentera un nouveau plan pluriannuel : le groupe devrait se s\u00e9parer d&rsquo;autres pays, dont peut-\u00eatre la Belgique.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La Belgique sous la loupe<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9taillant n&rsquo;a encore rien communiqu\u00e9 officiellement, mais selon les m\u00e9dias fran\u00e7ais, <a href=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-examine-effectivement-des-options-pour-la-belgique\/\">le groupe aurait mandat\u00e9 la banque d&rsquo;affaires Rothschild pour \u00e9tudier les options strat\u00e9giques<\/a>. Dans son rapport annuel, Carrefour qualifie la croissance du chiffre d&rsquo;affaires belge de \u00ab r\u00e9siliente malgr\u00e9 une forte concurrence \u00bb : sur une base comparable, le chiffre d&rsquo;affaires a augment\u00e9 de 0,2 % au quatri\u00e8me trimestre et de 0,8 % sur l&rsquo;ensemble de l&rsquo;ann\u00e9e. Un an plus t\u00f4t, on observait encore une contraction.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans un communiqu\u00e9 de presse s\u00e9par\u00e9, Carrefour Belgique \u00e9voque en outre \u00ab une am\u00e9lioration de la rentabilit\u00e9 \u00bb. \u00ab Les performances de 2025 prouvent la valeur du mod\u00e8le unique de Carrefour en Belgique \u00bb, peut-on lire dans un communiqu\u00e9 rassurant. \u00ab Cette base solide donne \u00e0 Carrefour toute confiance pour poursuivre sa cr\u00e9ation de valeur en 2026 avec le d\u00e9ploiement de sa nouvelle strat\u00e9gie 2026-2028. \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Carrefour cl\u00f4ture l&rsquo;ann\u00e9e 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe fran\u00e7ais de distribution a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d&rsquo;affaires, mais a subi l&rsquo;impact des taux de change et des co\u00fbts d&rsquo;int\u00e9gration. Le PDG Alexandre Bompard affiche toutefois sa confiance et promet un plan radicalement nouveau.<\/p>\n","protected":false},"author":5,"featured_media":142369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[18,24],"tags":[],"people":[],"extra":[43],"company":[87],"topic":[266],"region":[342],"class_list":["post-142368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","extra-plus","company-carrefour","topic-resultats-financiers","region-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique - RetailDetail BE<\/title>\n<meta name=\"description\" content=\"Carrefour cl\u00f4ture 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d&#039;affaires, mais a subi des co\u00fbts d&#039;int\u00e9gration.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"Carrefour cl\u00f4ture 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d&#039;affaires, mais a subi des co\u00fbts d&#039;int\u00e9gration.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-17T17:53:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T08:35:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1117\" \/>\n\t<meta property=\"og:image:height\" content=\"686\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pauline Neerman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pauline Neerman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/\"},\"author\":{\"name\":\"Pauline Neerman\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/66b54803fa10759039079458ea89e307\"},\"headline\":\"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique\",\"datePublished\":\"2026-02-17T17:53:33+00:00\",\"dateModified\":\"2026-02-18T08:35:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/\"},\"wordCount\":547,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/carrefour-hyper-1-1.jpg\",\"articleSection\":[\"Food\",\"Food\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/\",\"name\":\"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/carrefour-hyper-1-1.jpg\",\"datePublished\":\"2026-02-17T17:53:33+00:00\",\"dateModified\":\"2026-02-18T08:35:40+00:00\",\"description\":\"Carrefour cl\u00f4ture 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d'affaires, mais a subi des co\u00fbts d'int\u00e9gration.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/carrefour-hyper-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/carrefour-hyper-1-1.jpg\",\"width\":1117,\"height\":686,\"caption\":\"Carrefour Belgium\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/66b54803fa10759039079458ea89e307\",\"name\":\"Pauline Neerman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"caption\":\"Pauline Neerman\"},\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/paulineneerman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique - RetailDetail BE","description":"Carrefour cl\u00f4ture 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d'affaires, mais a subi des co\u00fbts d'int\u00e9gration.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/","og_locale":"fr_FR","og_type":"article","og_title":"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique - RetailDetail BE","og_description":"Carrefour cl\u00f4ture 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d'affaires, mais a subi des co\u00fbts d'int\u00e9gration.","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/","og_site_name":"RetailDetail BE","article_published_time":"2026-02-17T17:53:33+00:00","article_modified_time":"2026-02-18T08:35:40+00:00","og_image":[{"width":1117,"height":686,"url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg","type":"image\/jpeg"}],"author":"Pauline Neerman","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pauline Neerman","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/"},"author":{"name":"Pauline Neerman","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/66b54803fa10759039079458ea89e307"},"headline":"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique","datePublished":"2026-02-17T17:53:33+00:00","dateModified":"2026-02-18T08:35:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/"},"wordCount":547,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg","articleSection":["Food","Food"],"inLanguage":"fr-FR","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/","name":"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg","datePublished":"2026-02-17T17:53:33+00:00","dateModified":"2026-02-18T08:35:40+00:00","description":"Carrefour cl\u00f4ture 2025 avec des r\u00e9sultats mitig\u00e9s : le groupe a enregistr\u00e9 une l\u00e9g\u00e8re croissance de son chiffre d'affaires, mais a subi des co\u00fbts d'int\u00e9gration.","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg","width":1117,"height":686,"caption":"Carrefour Belgium"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/carrefour-reprise-dans-les-pays-cles-ainsi-que-la-belgique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Carrefour : reprise dans les \u00ab pays coeur \u00bb, ainsi que la Belgique"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/66b54803fa10759039079458ea89e307","name":"Pauline Neerman","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","caption":"Pauline Neerman"},"url":"https:\/\/www.retaildetail.be\/fr\/author\/paulineneerman\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2026\/02\/carrefour-hyper-1-1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/142368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=142368"}],"version-history":[{"count":2,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/142368\/revisions"}],"predecessor-version":[{"id":142384,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/142368\/revisions\/142384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/142369"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=142368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=142368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=142368"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=142368"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=142368"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=142368"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=142368"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=142368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}