{"id":31053,"date":"2019-02-04T10:03:33","date_gmt":"2019-02-04T10:03:33","guid":{"rendered":"https:\/\/www.retaildetail.be\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/"},"modified":"2019-02-04T10:03:33","modified_gmt":"2019-02-04T10:03:33","slug":"les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/","title":{"rendered":"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ?"},"content":{"rendered":"<p>La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Le parti a donc d\u00e9pos\u00e9 une proposition de loi qui met fin \u00e0 la journ\u00e9e de fermeture obligatoire. Les organisations pour ind\u00e9pendants ne sont pas favorables \u00e0 cette id\u00e9e.<\/p>\n<p><!--break--><\/p>\n<h2>\u00a0<br \/>\nAbandon des jours et heures de fermeture obligatoires<\/h2>\n<p>Les d\u00e9put\u00e9s Valerie Van Peel et Werner Janssen ont pr\u00e9sent\u00e9 un projet de loi visant \u00e0 modifier la loi sur les heures d&rsquo;ouverture. Ils souhaitent supprimer le jour de fermeture obligatoire ainsi que la restriction quant aux heures d\u2019ouverture. Le parti souhaite que les magasins puissent rester ouverts jusqu&rsquo;\u00e0 21 heures s&rsquo;ils le souhaitent.<\/p>\n<p>\u00a0<\/p>\n<p>Aujourd\u2019hui, le nombre d&rsquo;ouvertures le dimanche est limit\u00e9 et les heures d\u2019ouverture des magasins se situent entre 5h et 20h. Ce n&rsquo;est que le vendredi et la veille d&rsquo;un jour f\u00e9ri\u00e9 que les commerces peuvent garder leurs portes ouvertes jusqu&rsquo;\u00e0 21 h. Il existe n\u00e9anmoins une exception pour les magasins situ\u00e9s dans les centres touristiques reconnus.<\/p>\n<p>\u00a0<\/p>\n<p>La N-VA affirme vouloir donner plus de libert\u00e9 aux commer\u00e7ants, tandis que la proposition devrait offrir davantage de flexibilit\u00e9 aux consommateurs aussi. \u00ab Le nombre de couples dont les 2 partenaires travaillent, est en augmentation. Cela repr\u00e9sente un d\u00e9fi quotidien pour de nombreuses personnes. Le gouvernement souhaite <a href=\"http:\/\/www.standaard.be\/cnt\/dmf20190203_04149435\" target=\"_blank\" rel=\"noopener\">aider ces gens en offrant davantage de flexibilit\u00e9<\/a>. En gardant les magasins ouverts plus longtemps, il vous restera plus de temps \u00e0 consacrer \u00e0 vos enfants \u00bb, pr\u00e9cise Van Peel au journal De Standaard.<\/p>\n<p>\u00a0<\/p>\n<h2>70% des commer\u00e7ants s\u2019y opposent<\/h2>\n<p>Le Syndicat Neutre pour Ind\u00e9pendants et Unizo ne se r\u00e9jouissent pas de cette proposition. \u00ab Nous sommes absolument contre cette proposition et nous ne sommes pas les seuls \u00bb, d\u00e9clare Danny Van Assche d&rsquo;Unizo en termes tr\u00e8s clairs. \u00ab Une enqu\u00eate men\u00e9e \u00e0 la fin de l&rsquo;ann\u00e9e derni\u00e8re dans l&rsquo;ensemble du secteur a d\u00e9montr\u00e9 que plus de 70% des commer\u00e7ants se sont prononc\u00e9s contre la prolongation des heures d&rsquo;ouverture et l&rsquo;abolition du jour de fermeture obligatoire. \u00bb<br \/>\n\u00a0<\/p>\n<p>\u00ab L&rsquo;\u00e9largissement des heures d&rsquo;ouverture ne parviendra pas \u00e0 offrir plus de libert\u00e9 et un meilleur \u00e9quilibre entre la vie professionnelle et vie priv\u00e9e aux commer\u00e7ants. D\u2019autre part, cela n\u2019engendra aucune hausse du chiffre d&rsquo;affaires. Un consommateur ne peut d\u00e9penser son euro qu&rsquo;une seule fois, alors que d&rsquo;autres co\u00fbts vont s\u2019accumuler \u00bb explique \u00e9galement le SNI. En parlant de co\u00fbts, l&rsquo;organisation se r\u00e9f\u00e8re principalement aux frais de personnel. Le SNI souligne que la l\u00e9gislation sur le travail le dimanche devrait \u00e9galement changer, alors qu\u2019il serait plut\u00f4t pr\u00e9f\u00e9rable que le gouvernement soutienne davantage l\u2019e-commerce.<br \/>\n\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Le parti a donc d\u00e9pos\u00e9 une proposition de loi qui met fin \u00e0 la journ\u00e9e de fermeture obligatoire. Les organisations pour ind\u00e9pendants ne sont pas favorables \u00e0 cette id\u00e9e. \u00a0 Abandon des jours et heures de fermeture obligatoires Les d\u00e9put\u00e9s Valerie Van [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[25],"tags":[],"people":[],"extra":[],"company":[],"topic":[],"region":[],"class_list":["post-31053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ? - RetailDetail BE<\/title>\n<meta name=\"description\" content=\"La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Les organisations pour ind\u00e9pendants ne sont cependant pas favorables \u00e0 cette id\u00e9e.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ? - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Les organisations pour ind\u00e9pendants ne sont cependant pas favorables \u00e0 cette id\u00e9e.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-04T10:03:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg?fit=1000%2C668&quality=100&strip=all&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dev@grandiz.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"dev@grandiz.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/\"},\"author\":{\"name\":\"dev@grandiz.com\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/ba2d383452a753a3a1ce8cdb349b5fc9\"},\"headline\":\"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ?\",\"datePublished\":\"2019-02-04T10:03:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/\"},\"wordCount\":471,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/shutterstock_723576868_0.jpg\",\"articleSection\":[\"G\u00e9n\u00e9ral\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/\",\"name\":\"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ? - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/shutterstock_723576868_0.jpg\",\"datePublished\":\"2019-02-04T10:03:33+00:00\",\"description\":\"La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Les organisations pour ind\u00e9pendants ne sont cependant pas favorables \u00e0 cette id\u00e9e.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/shutterstock_723576868_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/shutterstock_723576868_0.jpg\",\"width\":1000,\"height\":668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/general\\\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/ba2d383452a753a3a1ce8cdb349b5fc9\",\"name\":\"dev@grandiz.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"caption\":\"dev@grandiz.com\"},\"sameAs\":[\"http:\\\/\\\/preprod.retaildetail.be\"],\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/devgrandiz-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ? - RetailDetail BE","description":"La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Les organisations pour ind\u00e9pendants ne sont cependant pas favorables \u00e0 cette id\u00e9e.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ? - RetailDetail BE","og_description":"La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Les organisations pour ind\u00e9pendants ne sont cependant pas favorables \u00e0 cette id\u00e9e.","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/","og_site_name":"RetailDetail BE","article_published_time":"2019-02-04T10:03:33+00:00","og_image":[{"width":1000,"height":668,"url":"https:\/\/i0.wp.com\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg?fit=1000%2C668&quality=100&strip=all&ssl=1","type":"image\/jpeg"}],"author":"dev@grandiz.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"dev@grandiz.com","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/"},"author":{"name":"dev@grandiz.com","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/ba2d383452a753a3a1ce8cdb349b5fc9"},"headline":"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ?","datePublished":"2019-02-04T10:03:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/"},"wordCount":471,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg","articleSection":["G\u00e9n\u00e9ral"],"inLanguage":"fr-FR","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/","name":"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ? - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg","datePublished":"2019-02-04T10:03:33+00:00","description":"La N-VA estime que les heures et jours de fermeture fixes sont d\u00e9pass\u00e9s. Les organisations pour ind\u00e9pendants ne sont cependant pas favorables \u00e0 cette id\u00e9e.","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg","width":1000,"height":668},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/general\/les-magasins-seront-ils-bientot-ouverts-le-dimanche-et-jusqua-21h-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Les magasins seront-ils bient\u00f4t ouverts le dimanche et jusqu\u2019\u00e0 21h ?"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/ba2d383452a753a3a1ce8cdb349b5fc9","name":"dev@grandiz.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","caption":"dev@grandiz.com"},"sameAs":["http:\/\/preprod.retaildetail.be"],"url":"https:\/\/www.retaildetail.be\/fr\/author\/devgrandiz-com\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/shutterstock_723576868_0.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/31053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=31053"}],"version-history":[{"count":0,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/31053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/31050"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=31053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=31053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=31053"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=31053"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=31053"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=31053"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=31053"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=31053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}