{"id":49372,"date":"2021-06-15T17:00:50","date_gmt":"2021-06-15T17:00:50","guid":{"rendered":"https:\/\/www.retaildetail.be\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/"},"modified":"2021-06-15T17:00:50","modified_gmt":"2021-06-15T17:00:50","slug":"colruyt-group-sous-pression-sa-part-de-marche-est-en-recul","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/","title":{"rendered":"Colruyt Group sous pression : sa part de march\u00e9 est en recul"},"content":{"rendered":"<p>Les r\u00e9sultats annuels de <strong>Colruyt Group <\/strong>montrent que les <strong>magasins Colruyt <\/strong>ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.<\/p>\n<p><!--break--><\/p>\n<p>\u00a0<\/p>\n<h2>Les magasins d\u2019alimentation perdent du terrain<\/h2>\n<p>Le chiffre d\u2019affaires de Colruyt Group a augment\u00e9 de 3,7\u00a0% \u00e0 9,9 milliards d\u2019euros lors de l\u2019exercice d\u00e9cal\u00e9 2020\/21. Hors carburants, la hausse du chiffre d\u2019affaires atteint \u00e0 6,4\u00a0% \u2013 Dats a en effet vu son chiffre d\u2019affaires baisser de plus de 25\u00a0%. La marge brute a augment\u00e9 \u00e0 28,1\u00a0% du chiffre d\u2019affaires, en partie gr\u00e2ce \u00e0 une baisse de pression promotionnelle. Mais les co\u00fbts ont \u00e9galement augment\u00e9 sous l\u2019effet des mesures sanitaires et d\u2019autres investissements.<\/p>\n<p>\nLes deux tendances se sont ainsi neutralis\u00e9es. Le r\u00e9sultat net atteint \u00e0 385 millions d\u2019euros, soit 3,9\u00a0% du chiffre d\u2019affaires \u2013 hors la plus-value enregistr\u00e9e par le groupe sur l\u2019apport d\u2019Eoly Energy dans un nouveau holding. Ces r\u00e9sultats sont inf\u00e9rieurs aux pr\u00e9visions des analystes. Au cours de l\u2019exercice pass\u00e9, le r\u00e9sultat net avait atteint 380 millions d\u2019euros, soit 4,0\u00a0% du chiffre d\u2019affaires.<br \/>\n\u00a0<\/p>\n<p>On attendait surtout les performances des magasins d\u2019alimentation Colruyt. Ses concurrents <strong>Delhaize<\/strong> et <strong>Carrefour<\/strong> avaient d\u00e9clar\u00e9 avoir gagn\u00e9 des parts de march\u00e9 au cours des derniers trimestres. Et en effet\u00a0: la part de march\u00e9 cumul\u00e9e des magasins d\u2019alimentation Colruyt Meilleurs Prix, <strong>OKay<\/strong> et <strong>Spar<\/strong> est retomb\u00e9e \u00e0 31,3\u00a0%, reconna\u00eet Colruyt Group. Elle \u00e9tait encore de 32,1\u00a0% au cours de l\u2019exercice 2019\/20. L\u2019explication est \u00e9vidente\u00a0: le groupe exploite proportionnellement moins de magasins de proximit\u00e9 que ses concurrents, et ces magasins de proximit\u00e9 ont largement surperform\u00e9 les autres formules retail pendant la crise sanitaire.<\/p>\n<p>\u00a0<\/p>\n<h2>\u00ab\u00a0Difficile \u00e0 \u00e9galer\u00a0\u00bb<\/h2>\n<p>Le chiffre d\u2019affaires de Colruyt en Belgique et au Luxembourg a progress\u00e9 de 3\u00a0% \u2013 mais de 0,7\u00a0% sur base comparable. Le chiffre d\u2019affaires cumul\u00e9 d\u2019OKay, Bio-Planet et Cru a augment\u00e9 de 6,0\u00a0%. Le chiffre d\u2019affaires du commerce de gros \u2013 qui inclut le chiffre d\u2019affaires des magasins Spar \u2013 a gagn\u00e9 15,5\u00a0% en Belgique et en France. Le grossiste food-service Solucious a vu son chiffre d\u2019affaires baisser de 13,4\u00a0%.<br \/>\n\u00a0<\/p>\n<p>Les ventes de d\u00e9tail dans le secteur non-food ont progress\u00e9\u00a0: elles ont gagn\u00e9 37,6\u00a0%, mais ce bond est principalement d\u00fb \u00e0 la consolidation compl\u00e8te de <strong>The Fashion Society<\/strong>, le holding propri\u00e9taire des cha\u00eenes de v\u00eatements <strong>ZEB<\/strong>, <strong>PointCarr\u00e9<\/strong>, <strong>The Fashion Store<\/strong> et <strong>ZEB For Stars<\/strong>. Le chiffre d\u2019affaires combin\u00e9 de <strong>Dreamland<\/strong>, <strong>Dreambaby<\/strong> et <strong>Bike Republic<\/strong> (anciennement Fiets!) a diminu\u00e9 de 2,7\u00a0% en raison des fermetures obligatoires. Les ventes en ligne sont en nette hausse tant dans le secteur food <strong>(Collect&amp;Go) <\/strong>que non-food, mais le d\u00e9taillant n\u2019a donn\u00e9 aucun d\u00e9tail \u00e0 ce sujet.<br \/>\n\u00a0<\/p>\n<p>Vu l\u2019incertitude li\u00e9e \u00e0 la crise sanitaire, Colruyt Group ne se risque pas \u00e0 faire des pr\u00e9visions concr\u00e8tes pour l\u2019exercice en cours. Toutefois, la soci\u00e9t\u00e9 indique que le r\u00e9sultat net consolid\u00e9 de l\u2019exercice pass\u00e9 serait \u00ab\u00a0difficile \u00e0 \u00e9galer\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines. \u00a0 Les magasins d\u2019alimentation perdent du terrain Le chiffre d\u2019affaires de Colruyt Group [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":49369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[],"people":[],"extra":[],"company":[],"topic":[],"region":[],"class_list":["post-49372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Colruyt Group sous pression : sa part de march\u00e9 est en recul - RetailDetail BE<\/title>\n<meta name=\"description\" content=\"Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Colruyt Group sous pression : sa part de march\u00e9 est en recul - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T17:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg?fit=1306%2C835&quality=100&strip=all&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1306\" \/>\n\t<meta property=\"og:image:height\" content=\"835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"dev@grandiz.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"dev@grandiz.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/\"},\"author\":{\"name\":\"dev@grandiz.com\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/ba2d383452a753a3a1ce8cdb349b5fc9\"},\"headline\":\"Colruyt Group sous pression : sa part de march\u00e9 est en recul\",\"datePublished\":\"2021-06-15T17:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Colruyt-kassa_1.jpg\",\"articleSection\":[\"Food\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/\",\"name\":\"Colruyt Group sous pression : sa part de march\u00e9 est en recul - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Colruyt-kassa_1.jpg\",\"datePublished\":\"2021-06-15T17:00:50+00:00\",\"description\":\"Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Colruyt-kassa_1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Colruyt-kassa_1.jpg\",\"width\":1306,\"height\":835},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colruyt Group sous pression : sa part de march\u00e9 est en recul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/ba2d383452a753a3a1ce8cdb349b5fc9\",\"name\":\"dev@grandiz.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"caption\":\"dev@grandiz.com\"},\"sameAs\":[\"http:\\\/\\\/preprod.retaildetail.be\"],\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/devgrandiz-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Colruyt Group sous pression : sa part de march\u00e9 est en recul - RetailDetail BE","description":"Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/","og_locale":"fr_FR","og_type":"article","og_title":"Colruyt Group sous pression : sa part de march\u00e9 est en recul - RetailDetail BE","og_description":"Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/","og_site_name":"RetailDetail BE","article_published_time":"2021-06-15T17:00:50+00:00","og_image":[{"width":1306,"height":835,"url":"https:\/\/i0.wp.com\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg?fit=1306%2C835&quality=100&strip=all&ssl=1","type":"image\/jpeg"}],"author":"dev@grandiz.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"dev@grandiz.com","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/"},"author":{"name":"dev@grandiz.com","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/ba2d383452a753a3a1ce8cdb349b5fc9"},"headline":"Colruyt Group sous pression : sa part de march\u00e9 est en recul","datePublished":"2021-06-15T17:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/"},"wordCount":520,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg","articleSection":["Food"],"inLanguage":"fr-FR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/","name":"Colruyt Group sous pression : sa part de march\u00e9 est en recul - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg","datePublished":"2021-06-15T17:00:50+00:00","description":"Les r\u00e9sultats annuels de Colruyt Group montrent que les magasins Colruyt ont perdu des parts de march\u00e9 \u00e0 la suite de la crise sanitaire. Le chiffre d\u2019affaires fr\u00f4le la barre des dix milliards d\u2019euros et les pr\u00e9visions de b\u00e9n\u00e9fices sont tr\u00e8s incertaines.","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg","width":1306,"height":835},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/colruyt-group-sous-pression-sa-part-de-marche-est-en-recul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Colruyt Group sous pression : sa part de march\u00e9 est en recul"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/ba2d383452a753a3a1ce8cdb349b5fc9","name":"dev@grandiz.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","caption":"dev@grandiz.com"},"sameAs":["http:\/\/preprod.retaildetail.be"],"url":"https:\/\/www.retaildetail.be\/fr\/author\/devgrandiz-com\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/Colruyt-kassa_1.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/49372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=49372"}],"version-history":[{"count":0,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/49372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/49369"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=49372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=49372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=49372"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=49372"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=49372"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=49372"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=49372"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=49372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}