{"id":57674,"date":"2022-06-03T09:28:02","date_gmt":"2022-06-03T07:28:02","guid":{"rendered":"https:\/\/www.retaildetail.be\/?p=57674"},"modified":"2022-06-03T09:28:03","modified_gmt":"2022-06-03T07:28:03","slug":"capri-le-proprietaire-de-versace-bat-tous-les-records","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/","title":{"rendered":"Capri, le propri\u00e9taire de Versace, bat tous les records"},"content":{"rendered":"\n<p><strong>Capri<\/strong>, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022. Apr\u00e8s une perte l&rsquo;ann\u00e9e derni\u00e8re, Capri a enregistr\u00e9 un b\u00e9n\u00e9fice net de 823 millions de dollars (770 millions d&rsquo;euros), tandis que le chiffre d&rsquo;affaires a augment\u00e9 d&rsquo;un quart pour atteindre 5,7 milliards de dollars (5,3 milliards d&rsquo;euros).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Des records<\/h2>\n\n\n\n<p>Comme de nombreuses entreprises de luxe, Capri ne semble pas du tout souffrir de la crise. Au cours de l&rsquo;exercice 2022, qui s&rsquo;est termin\u00e9 en avril, les ventes de la soci\u00e9t\u00e9 holding ont atteint des niveaux records. Au cours du dernier trimestre, alors que la guerre en Ukraine et la hausse de l&rsquo;inflation jouaient d\u00e9j\u00e0 un r\u00f4le majeur, les ventes ont augment\u00e9 de 24,6 %. La barre du milliard et demi de dollars, soit 1,4 milliard d&rsquo;euros, a \u00e9t\u00e9 manqu\u00e9e de justesse. La part du lion est venue de Michael Kors. Versace (315 millions de dollars, +34%) et Jimmy Choo (156 millions de dollars, +26%) ont r\u00e9alis\u00e9 moins de chiffre d&rsquo;affaires, mais ont r\u00e9ussi \u00e0 cro\u00eetre plus rapidement.<\/p>\n\n\n\n<p>Le PDG John Idol est \u2018fier\u2019 des performances de ses maisons de luxe : \u00ab&nbsp;Capri Holdings a r\u00e9alis\u00e9 le chiffre d&rsquo;affaires, la marge b\u00e9n\u00e9ficiaire et le b\u00e9n\u00e9fice par action les plus \u00e9lev\u00e9s de son histoire. En outre, notre flux de tr\u00e9sorerie est solide et nous avons pu distribuer 650 millions de dollars \u00e0 nos actionnaires. Ces r\u00e9sultats records &#8211; obtenus face \u00e0 une pand\u00e9mie sans pr\u00e9c\u00e9dent &#8211; d\u00e9montrent la force de nos marques et le succ\u00e8s de nos initiatives strat\u00e9giques&nbsp;\u00bb, a d\u00e9clar\u00e9 le directeur g\u00e9n\u00e9ral dans un communiqu\u00e9 de presse.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A sept milliards<\/h2>\n\n\n\n<p>Pour le nouvel exercice, Capri s&rsquo;attend \u00e0 un ralentissement de la croissance des ventes : avec 5 % de plus, la barre des six milliards de dollars ne sera pas atteinte. Les marges devraient \u00e9galement rester \u00e0 peu pr\u00e8s identiques, \u00e0 18 %. \u00c0 plus long terme, le PDG Idol est confiant : \u00ab&nbsp;Si les vents contraires financiers actuels cessent, nous devrions rapidement retrouver une croissance \u00e0 deux chiffres. Gr\u00e2ce \u00e0 la force de nos marques, nous voulons atteindre \u00e0 terme un chiffre d&rsquo;affaires de sept milliards de dollars et une marge b\u00e9n\u00e9ficiaire op\u00e9rationnelle de 20 %.&nbsp;\u00bb<\/p>\n\n\n\n<p>Capri Holdings <a href=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/michael-kors-rachete-versace-et-devient-capri-holdings-2\/\">est n\u00e9e d\u00e9but 2019<\/a> de la fusion de Versace et Michael Kors, ce dernier ayant \u00e9galement acquis Jimmy Choo bien un an plus t\u00f4t. Les marques de luxe <a href=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/versace-repond-aux-attentes-avec-66-de-baisse-du-chiffre-daffaires\/\">ont certes souffert au d\u00e9but de la pand\u00e9mie<\/a>, mais elles ont r\u00e9ussi \u00e0 se r\u00e9tablir tr\u00e8s rapidement.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022. Apr\u00e8s une perte l&rsquo;ann\u00e9e derni\u00e8re, Capri a enregistr\u00e9 un b\u00e9n\u00e9fice net de 823 millions de dollars (770 millions d&rsquo;euros), tandis que le chiffre d&rsquo;affaires a augment\u00e9 d&rsquo;un quart pour atteindre 5,7 milliards de dollars (5,3 milliards d&rsquo;euros).<\/p>\n","protected":false},"author":4,"featured_media":57663,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22],"tags":[],"people":[],"extra":[],"company":[552],"topic":[266],"region":[],"class_list":["post-57674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode","company-capri","topic-resultats-financiers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Capri, le propri\u00e9taire de Versace, bat tous les records - RetailDetail BE<\/title>\n<meta name=\"description\" content=\"Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capri, le propri\u00e9taire de Versace, bat tous les records - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-03T07:28:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-06-03T07:28:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maarten Reul\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maarten Reul\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/\"},\"author\":{\"name\":\"Maarten Reul\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/fbcf88ed1b121d65026767275bff632f\"},\"headline\":\"Capri, le propri\u00e9taire de Versace, bat tous les records\",\"datePublished\":\"2022-06-03T07:28:02+00:00\",\"dateModified\":\"2022-06-03T07:28:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/\"},\"wordCount\":450,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Michael-Kors-shutterstock_675249112.jpg\",\"articleSection\":[\"Mode\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/\",\"name\":\"Capri, le propri\u00e9taire de Versace, bat tous les records - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Michael-Kors-shutterstock_675249112.jpg\",\"datePublished\":\"2022-06-03T07:28:02+00:00\",\"dateModified\":\"2022-06-03T07:28:03+00:00\",\"description\":\"Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Michael-Kors-shutterstock_675249112.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Michael-Kors-shutterstock_675249112.jpg\",\"width\":1000,\"height\":750,\"caption\":\"Shutterstock.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/capri-le-proprietaire-de-versace-bat-tous-les-records\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capri, le propri\u00e9taire de Versace, bat tous les records\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/fbcf88ed1b121d65026767275bff632f\",\"name\":\"Maarten Reul\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80ddb4599c879961a4ed95ba7bc448a3e7570fae5c1c49a42c5261794f16d9a6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80ddb4599c879961a4ed95ba7bc448a3e7570fae5c1c49a42c5261794f16d9a6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/80ddb4599c879961a4ed95ba7bc448a3e7570fae5c1c49a42c5261794f16d9a6?s=96&d=mm&r=g\",\"caption\":\"Maarten Reul\"},\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/maartenreul\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capri, le propri\u00e9taire de Versace, bat tous les records - RetailDetail BE","description":"Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/","og_locale":"fr_FR","og_type":"article","og_title":"Capri, le propri\u00e9taire de Versace, bat tous les records - RetailDetail BE","og_description":"Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022.","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/","og_site_name":"RetailDetail BE","article_published_time":"2022-06-03T07:28:02+00:00","article_modified_time":"2022-06-03T07:28:03+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg","type":"image\/jpeg"}],"author":"Maarten Reul","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Maarten Reul","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/"},"author":{"name":"Maarten Reul","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/fbcf88ed1b121d65026767275bff632f"},"headline":"Capri, le propri\u00e9taire de Versace, bat tous les records","datePublished":"2022-06-03T07:28:02+00:00","dateModified":"2022-06-03T07:28:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/"},"wordCount":450,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg","articleSection":["Mode"],"inLanguage":"fr-FR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/","name":"Capri, le propri\u00e9taire de Versace, bat tous les records - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg","datePublished":"2022-06-03T07:28:02+00:00","dateModified":"2022-06-03T07:28:03+00:00","description":"Capri, qui regroupe les marques de luxe Jimmy Choo, Michael Kors et Versace, a atteint des chiffres records pour son exercice 2022.","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg","width":1000,"height":750,"caption":"Shutterstock.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/capri-le-proprietaire-de-versace-bat-tous-les-records\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Capri, le propri\u00e9taire de Versace, bat tous les records"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/fbcf88ed1b121d65026767275bff632f","name":"Maarten Reul","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/80ddb4599c879961a4ed95ba7bc448a3e7570fae5c1c49a42c5261794f16d9a6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/80ddb4599c879961a4ed95ba7bc448a3e7570fae5c1c49a42c5261794f16d9a6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/80ddb4599c879961a4ed95ba7bc448a3e7570fae5c1c49a42c5261794f16d9a6?s=96&d=mm&r=g","caption":"Maarten Reul"},"url":"https:\/\/www.retaildetail.be\/fr\/author\/maartenreul\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/06\/Michael-Kors-shutterstock_675249112.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/57674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=57674"}],"version-history":[{"count":1,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/57674\/revisions"}],"predecessor-version":[{"id":57675,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/57674\/revisions\/57675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/57663"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=57674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=57674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=57674"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=57674"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=57674"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=57674"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=57674"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=57674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}