{"id":66402,"date":"2022-11-03T16:13:05","date_gmt":"2022-11-03T15:13:05","guid":{"rendered":"https:\/\/www.retaildetail.be\/?p=66402"},"modified":"2022-11-03T16:13:07","modified_gmt":"2022-11-03T15:13:07","slug":"hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/","title":{"rendered":"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement"},"content":{"rendered":"\n<p><strong>Hugo Boss<\/strong> rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n&rsquo;ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Attirer les jeunes<\/h2>\n\n\n\n<p>Hugo Boss s&rsquo;est remarquablement bien comport\u00e9 au dernier trimestre. La marque allemande, surtout connue pour ses costumes pour hommes, s&rsquo;est r\u00e9cemment tourn\u00e9e vers les jeunes et les v\u00eatements plus d\u00e9contract\u00e9s. Par cons\u00e9quent, le d\u00e9fil\u00e9 de la Fashion Week \u00e0 Milan a \u00e9t\u00e9 tr\u00e8s suivi sur les r\u00e9seaux sociaux. Les ventes de ses collections pour femmes connaissent \u00e9galement une croissance plus rapide.<\/p>\n\n\n\n<p>Au troisi\u00e8me trimestre, le chiffre d&rsquo;affaires a ainsi augment\u00e9 de 18 % pour atteindre 933 millions d&rsquo;euros, soit le plus haut niveau de l&rsquo;histoire de l&rsquo;entreprise. Une croissance \u00e0 deux chiffres a \u00e9t\u00e9 enregistr\u00e9e dans toutes les r\u00e9gions du monde, mais l&rsquo;Asie en particulier est de nouveau sur les rails apr\u00e8s la pand\u00e9mie Covid. La r\u00e9gion a enregistr\u00e9 33 % de ventes suppl\u00e9mentaires. Les ventes physiques ont \u00e9galement augment\u00e9 d&rsquo;un quart par rapport \u00e0 la p\u00e9riode pr\u00e9-Covid en 2019. L&rsquo;EBIT a augment\u00e9 de 8 % pour atteindre 92 millions d&rsquo;euros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Encore trop prudent<\/h2>\n\n\n\n<p>Hugo Boss revoit donc \u00e0 la hausse ses perspectives pour l&rsquo;ensemble de l&rsquo;ann\u00e9e : l&rsquo;entreprise table d\u00e9sormais sur des ventes en hausse de 30 % et un b\u00e9n\u00e9fice d&rsquo;exploitation (EBIT) m\u00eame sup\u00e9rieur de 45 % \u00e0 celui de l&rsquo;ann\u00e9e derni\u00e8re. Bien que les investisseurs et les analystes de Bloomberg pensent que cette pr\u00e9vision est trop prudente, notamment en raison de la vigueur du troisi\u00e8me trimestre.<\/p>\n\n\n\n<p>La semaine derni\u00e8re, le groupe de distribution britannique <strong>Frasers <\/strong>a annonc\u00e9 qu&rsquo;il augmentait sa participation dans la marque allemande. La holding de distribution de l&rsquo;homme d&rsquo;affaires Mike Ashley (\u00e9galement propri\u00e9taire de <strong>Sports Direct<\/strong>, entre autres) d\u00e9tient d\u00e9sormais une participation d&rsquo;un peu moins de 33 % dans Hugo Boss.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n&rsquo;ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.<\/p>\n","protected":false},"author":5,"featured_media":31329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22],"tags":[],"people":[],"extra":[],"company":[715],"topic":[266],"region":[470],"class_list":["post-66402","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode","company-hugo-boss","topic-resultats-financiers","region-allemagne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement - RetailDetail BE<\/title>\n<meta name=\"description\" content=\"Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n&#039;ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n&#039;ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-03T15:13:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-03T15:13:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"588\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pauline Neerman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pauline Neerman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/\"},\"author\":{\"name\":\"Pauline Neerman\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/66b54803fa10759039079458ea89e307\"},\"headline\":\"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement\",\"datePublished\":\"2022-11-03T15:13:05+00:00\",\"dateModified\":\"2022-11-03T15:13:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/\"},\"wordCount\":347,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hugo_boss_retail_antwerpen.jpg\",\"articleSection\":[\"Mode\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/\",\"name\":\"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hugo_boss_retail_antwerpen.jpg\",\"datePublished\":\"2022-11-03T15:13:05+00:00\",\"dateModified\":\"2022-11-03T15:13:07+00:00\",\"description\":\"Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n'ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hugo_boss_retail_antwerpen.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/hugo_boss_retail_antwerpen.jpg\",\"width\":800,\"height\":588},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/66b54803fa10759039079458ea89e307\",\"name\":\"Pauline Neerman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"caption\":\"Pauline Neerman\"},\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/paulineneerman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement - RetailDetail BE","description":"Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n'ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/","og_locale":"fr_FR","og_type":"article","og_title":"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement - RetailDetail BE","og_description":"Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n'ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/","og_site_name":"RetailDetail BE","article_published_time":"2022-11-03T15:13:05+00:00","article_modified_time":"2022-11-03T15:13:07+00:00","og_image":[{"width":800,"height":588,"url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg","type":"image\/jpeg"}],"author":"Pauline Neerman","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pauline Neerman","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/"},"author":{"name":"Pauline Neerman","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/66b54803fa10759039079458ea89e307"},"headline":"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement","datePublished":"2022-11-03T15:13:05+00:00","dateModified":"2022-11-03T15:13:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/"},"wordCount":347,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg","articleSection":["Mode"],"inLanguage":"fr-FR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/","name":"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg","datePublished":"2022-11-03T15:13:05+00:00","dateModified":"2022-11-03T15:13:07+00:00","description":"Hugo Boss rel\u00e8ve les attentes apr\u00e8s un trimestre record : jamais les ventes n'ont \u00e9t\u00e9 aussi \u00e9lev\u00e9es. La marque de mode allemande fait une cure de rajeunissement, qui porte visiblement ses fruits.","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg","width":800,"height":588},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/hugo-boss-enregistre-des-ventes-record-apres-une-cure-de-rajeunissement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Hugo Boss enregistre des ventes record apr\u00e8s une cure de rajeunissement"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/66b54803fa10759039079458ea89e307","name":"Pauline Neerman","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","caption":"Pauline Neerman"},"url":"https:\/\/www.retaildetail.be\/fr\/author\/paulineneerman\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/hugo_boss_retail_antwerpen.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/66402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=66402"}],"version-history":[{"count":1,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/66402\/revisions"}],"predecessor-version":[{"id":66403,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/66402\/revisions\/66403"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/31329"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=66402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=66402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=66402"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=66402"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=66402"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=66402"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=66402"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=66402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}