{"id":75585,"date":"2023-04-05T14:32:13","date_gmt":"2023-04-05T12:32:13","guid":{"rendered":"https:\/\/www.retaildetail.be\/?p=75585"},"modified":"2023-04-05T14:32:16","modified_gmt":"2023-04-05T12:32:16","slug":"la-salmonelle-continue-de-peser-sur-barry-callebaut","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/","title":{"rendered":"La salmonelle continue de peser sur Barry Callebaut"},"content":{"rendered":"\n<p><strong>Barry Callebaut<\/strong> a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 une infection \u00e0 la salmonelle qui a entra\u00een\u00e9 l&rsquo;arr\u00eat temporaire de l&rsquo;usine de Wieze. Un nouveau PDG prend le relais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Moins de chocolat<\/h2>\n\n\n\n<p>Le fournisseur de chocolat Barry Callebaut a livr\u00e9 2,9 % de chocolat en moins au cours du semestre bris\u00e9 2022\/23. L&rsquo;\u00e9pid\u00e9mie de <a href=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-fermeture-de-son-usine-belge-donne-la-gueule-de-bois-financiere-a-barry-callebaut\/\" target=\"_blank\" rel=\"noreferrer noopener\">salmonelles dans l&rsquo;usine belge de Wieze<\/a> ayant continu\u00e9 \u00e0 se faire sentir pendant longtemps, le volume a en fait baiss\u00e9 de 5,1 % au premier trimestre.<\/p>\n\n\n\n<p>Mais m\u00eame sans l&rsquo;effet de red\u00e9marrage \u00e0 Wieze, moins de chocolat a \u00e9t\u00e9 vendu : -1,8 %, \u00ab en ligne avec le march\u00e9 mondial sous-jacent des produits de chocolat \u00bb. En raison de l&rsquo;inflation, la demande a \u00e9t\u00e9 plus faible que pr\u00e9vu, explique le directeur financier Ben De Schryver. Au deuxi\u00e8me trimestre, le volume s&rsquo;est progressivement r\u00e9tabli.<\/p>\n\n\n\n<p>Les ventes ont ainsi atteint 4,2 milliards de francs suisses (4,24 milliards d&rsquo;euros), ce qui repr\u00e9sente une croissance de 7,9 % en monnaie locale. Barry Callebaut est particuli\u00e8rement satisfait de sa forte rentabilit\u00e9 : le b\u00e9n\u00e9fice net s&rsquo;est \u00e9lev\u00e9 \u00e0 234,3 millions de francs suisses, soit 10,4 % de plus que l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente en monnaie locale. De Schryver a fait l&rsquo;\u00e9loge du \u00ab leadership continu en mati\u00e8re de co\u00fbts \u00bb et de la bonne combinaison de produits du groupe.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Plut\u00f4t b\u00e9n\u00e9fices que croissance<\/h2>\n\n\n\n<p>Pour l&rsquo;ensemble de l&rsquo;exercice, le fabricant de chocolat table d\u00e9sormais sur une croissance stable ou modeste du volume et sur une forte rentabilit\u00e9 op\u00e9rationnelle (EBIT). Pour les trois prochaines ann\u00e9es \u00e9galement, le fournisseur aux marques de chocolat pense devoir compter principalement sur les b\u00e9n\u00e9fices, car les volumes augmenteront de moins de 5 % en moyenne.<\/p>\n\n\n\n<p>Avec effet imm\u00e9diat, le groupe Barry Callebaut a \u00e9galement un nouveau PDG. L&rsquo;Allemand Peter Feld succ\u00e8de \u00e0 Peter Boone, qui se retire pour des raisons personnelles avec effet imm\u00e9diat. Feld a plus de 30 ans d&rsquo;exp\u00e9rience dans des entreprises mondiales de biens et de services de consommation, comme P&amp;G et Jacobs entre autres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l&rsquo;infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.<\/p>\n","protected":false},"author":5,"featured_media":75530,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[24],"tags":[],"people":[],"extra":[],"company":[652],"topic":[266],"region":[885],"class_list":["post-75585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-food","company-barry-callebaut","topic-resultats-financiers","region-suisse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La salmonelle continue de peser sur Barry Callebaut - RetailDetail BE<\/title>\n<meta name=\"description\" content=\"Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l&#039;infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La salmonelle continue de peser sur Barry Callebaut - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l&#039;infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-05T12:32:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-05T12:32:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pauline Neerman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pauline Neerman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/\"},\"author\":{\"name\":\"Pauline Neerman\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/66b54803fa10759039079458ea89e307\"},\"headline\":\"La salmonelle continue de peser sur Barry Callebaut\",\"datePublished\":\"2023-04-05T12:32:13+00:00\",\"dateModified\":\"2023-04-05T12:32:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/\"},\"wordCount\":360,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg\",\"articleSection\":[\"Food\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/\",\"name\":\"La salmonelle continue de peser sur Barry Callebaut - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg\",\"datePublished\":\"2023-04-05T12:32:13+00:00\",\"dateModified\":\"2023-04-05T12:32:16+00:00\",\"description\":\"Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l'infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg\",\"width\":1440,\"height\":960,\"caption\":\"Nieuwe CEO Peter Feld\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/food\\\/la-salmonelle-continue-de-peser-sur-barry-callebaut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La salmonelle continue de peser sur Barry Callebaut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/66b54803fa10759039079458ea89e307\",\"name\":\"Pauline Neerman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g\",\"caption\":\"Pauline Neerman\"},\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/paulineneerman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La salmonelle continue de peser sur Barry Callebaut - RetailDetail BE","description":"Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l'infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/","og_locale":"fr_FR","og_type":"article","og_title":"La salmonelle continue de peser sur Barry Callebaut - RetailDetail BE","og_description":"Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l'infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/","og_site_name":"RetailDetail BE","article_published_time":"2023-04-05T12:32:13+00:00","article_modified_time":"2023-04-05T12:32:16+00:00","og_image":[{"width":1440,"height":960,"url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg","type":"image\/jpeg"}],"author":"Pauline Neerman","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pauline Neerman","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/"},"author":{"name":"Pauline Neerman","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/66b54803fa10759039079458ea89e307"},"headline":"La salmonelle continue de peser sur Barry Callebaut","datePublished":"2023-04-05T12:32:13+00:00","dateModified":"2023-04-05T12:32:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/"},"wordCount":360,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg","articleSection":["Food"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/","name":"La salmonelle continue de peser sur Barry Callebaut - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg","datePublished":"2023-04-05T12:32:13+00:00","dateModified":"2023-04-05T12:32:16+00:00","description":"Barry Callebaut a vendu moins de chocolat au cours des six derniers mois, suite \u00e0 l'infection \u00e0 la salmonelle. Un nouveau PDG prend le relais.","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg","width":1440,"height":960,"caption":"Nieuwe CEO Peter Feld"},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/food\/la-salmonelle-continue-de-peser-sur-barry-callebaut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"La salmonelle continue de peser sur Barry Callebaut"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/66b54803fa10759039079458ea89e307","name":"Pauline Neerman","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/58db22aee589a691f9603e5765ac06010427a923f9b2728b951eb7fe27214d70?s=96&d=mm&r=g","caption":"Pauline Neerman"},"url":"https:\/\/www.retaildetail.be\/fr\/author\/paulineneerman\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2023\/04\/Barry-Callebaut-Group-CEO-Peter-Feld-2023_0.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/75585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=75585"}],"version-history":[{"count":2,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/75585\/revisions"}],"predecessor-version":[{"id":75587,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/75585\/revisions\/75587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/75530"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=75585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=75585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=75585"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=75585"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=75585"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=75585"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=75585"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=75585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}