{"id":7835,"date":"2014-12-30T12:33:19","date_gmt":"2014-12-30T12:33:19","guid":{"rendered":"https:\/\/www.retaildetail.be\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/"},"modified":"2014-12-30T12:33:19","modified_gmt":"2014-12-30T12:33:19","slug":"la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30","status":"publish","type":"post","link":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/","title":{"rendered":"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30%"},"content":{"rendered":"<h2>Faible fin d\u2019ann\u00e9e, donc davantage de stock et fortes r\u00e9ductions<\/h2>\n<p>L\u2019Union des Classes Moyennes, le pendant francophone de l\u2019Unizo, a interrog\u00e9 278 commer\u00e7ants ind\u00e9pendants \u00e0 l\u2019approche des soldes d\u2019hiver, qui d\u00e9marrent le 3 janvier. Cette enqu\u00eate r\u00e9v\u00e8le que 48,5% d\u2019entre eux (soit pr\u00e8s d\u2019un commer\u00e7ant sur deux) se retrouvent avec davantage d\u2019invendus\u00a0 dans les rayons que l\u2019an dernier. Seuls 12,8% d\u00e9marrent les soldes avec un stock moins important.<\/p>\n<p>\u00ab Cela signifie donc que les ventes de fin d\u2019ann\u00e9es ont \u00e9t\u00e9 d\u00e9cevantes. L\u2019automne tr\u00e8s doux explique en partie cette situation, tout comme la faible confiance du consommateur \u00bb, affirme l\u2019UCM, qui confirme ainsi <a href=\"fr\/f-belgique\/bgq-mode\/item\/20582-bilan-morose-pour-la-saison-d-automne-des-commerces-de-mode\" target=\"_blank\" rel=\"noopener\">la tendance observ\u00e9e en Flandre<\/a>.<\/p>\n<p>Malgr\u00e9 ces stocks plus importants, seuls 20,9% des commer\u00e7ants pensent r\u00e9aliser un chiffre d\u2019affaire en hausse par rapport aux soldes d\u2019hiver pr\u00e9c\u00e9dentes, alors que 34,1% tablent sur un chiffre d\u2019affaires inf\u00e9rieur. \u00ab L\u2019explication r\u00e9side dans les rabais : d\u00e8s samedi plus de 4 boutiques sur dix accorderont des r\u00e9ductions de 30% ou plus : un pourcentage plus \u00e9lev\u00e9 que lors de pr\u00e9c\u00e9dents sondages \u00bb, indique l\u2019UCM.<\/p>\n<h2>\n<br \/>80% des commer\u00e7ants veulent maintenir les soldes<\/h2>\n<p>Selon l\u2019UCM, l\u2019octroi de fortes r\u00e9ductions d\u00e8s le d\u00e9but des soldes, est li\u00e9 \u00e0 la multiplication des\u00a0 r\u00e9ductions accord\u00e9es en dehors des mois de soldes de janvier et juillet, notamment les mid-sales ou encore les ventes coupl\u00e9es : 52,6% des boutiques interrog\u00e9es pratiquent ce type de r\u00e9ductions.<\/p>\n<p>Pourtant 82,2% des r\u00e9pondants souhaitent le maintien des soldes, car elles constituent le moyen id\u00e9al d\u2019\u00e9couler le stock invendu (67,8%) et d\u2019attirer de nouveaux clients (20,9%).<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faible fin d\u2019ann\u00e9e, donc davantage de stock et fortes r\u00e9ductions L\u2019Union des Classes Moyennes, le pendant francophone de l\u2019Unizo, a interrog\u00e9 278 commer\u00e7ants ind\u00e9pendants \u00e0 l\u2019approche des soldes d\u2019hiver, qui d\u00e9marrent le 3 janvier. Cette enqu\u00eate r\u00e9v\u00e8le que 48,5% d\u2019entre eux (soit pr\u00e8s d\u2019un commer\u00e7ant sur deux) se retrouvent avec davantage d\u2019invendus\u00a0 dans les rayons [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":84,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[22],"tags":[],"people":[],"extra":[],"company":[],"topic":[],"region":[],"class_list":["post-7835","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mode"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30% - RetailDetail BE<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30% - RetailDetail BE\" \/>\n<meta property=\"og:description\" content=\"Faible fin d\u2019ann\u00e9e, donc davantage de stock et fortes r\u00e9ductions L\u2019Union des Classes Moyennes, le pendant francophone de l\u2019Unizo, a interrog\u00e9 278 commer\u00e7ants ind\u00e9pendants \u00e0 l\u2019approche des soldes d\u2019hiver, qui d\u00e9marrent le 3 janvier. Cette enqu\u00eate r\u00e9v\u00e8le que 48,5% d\u2019entre eux (soit pr\u00e8s d\u2019un commer\u00e7ant sur deux) se retrouvent avec davantage d\u2019invendus\u00a0 dans les rayons [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/\" \/>\n<meta property=\"og:site_name\" content=\"RetailDetail BE\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-30T12:33:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png?fit=281%2C147&quality=100&strip=all&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"281\" \/>\n\t<meta property=\"og:image:height\" content=\"147\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"dev@grandiz.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"dev@grandiz.com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/\"},\"author\":{\"name\":\"dev@grandiz.com\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/ba2d383452a753a3a1ce8cdb349b5fc9\"},\"headline\":\"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30%\",\"datePublished\":\"2014-12-30T12:33:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/\"},\"wordCount\":301,\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"articleSection\":[\"Mode\"],\"inLanguage\":\"fr-FR\",\"copyrightYear\":\"2014\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/\",\"name\":\"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30% - RetailDetail BE\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"datePublished\":\"2014-12-30T12:33:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.png\",\"width\":281,\"height\":147},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/news\\\/mode\\\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"name\":\"RetailDetail BE\",\"description\":\"News\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#organization\",\"name\":\"RetailDetail BE\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.retaildetail.be\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/logo.svg\",\"width\":131,\"height\":70,\"caption\":\"RetailDetail BE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.retaildetail.be\\\/nl\\\/#\\\/schema\\\/person\\\/ba2d383452a753a3a1ce8cdb349b5fc9\",\"name\":\"dev@grandiz.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g\",\"caption\":\"dev@grandiz.com\"},\"sameAs\":[\"http:\\\/\\\/preprod.retaildetail.be\"],\"url\":\"https:\\\/\\\/www.retaildetail.be\\\/fr\\\/author\\\/devgrandiz-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30% - RetailDetail BE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/","og_locale":"fr_FR","og_type":"article","og_title":"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30% - RetailDetail BE","og_description":"Faible fin d\u2019ann\u00e9e, donc davantage de stock et fortes r\u00e9ductions L\u2019Union des Classes Moyennes, le pendant francophone de l\u2019Unizo, a interrog\u00e9 278 commer\u00e7ants ind\u00e9pendants \u00e0 l\u2019approche des soldes d\u2019hiver, qui d\u00e9marrent le 3 janvier. Cette enqu\u00eate r\u00e9v\u00e8le que 48,5% d\u2019entre eux (soit pr\u00e8s d\u2019un commer\u00e7ant sur deux) se retrouvent avec davantage d\u2019invendus\u00a0 dans les rayons [&hellip;]","og_url":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/","og_site_name":"RetailDetail BE","article_published_time":"2014-12-30T12:33:19+00:00","og_image":[{"width":281,"height":147,"url":"https:\/\/i0.wp.com\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png?fit=281%2C147&quality=100&strip=all&ssl=1","type":"image\/png"}],"author":"dev@grandiz.com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"dev@grandiz.com","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#article","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/"},"author":{"name":"dev@grandiz.com","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/ba2d383452a753a3a1ce8cdb349b5fc9"},"headline":"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30%","datePublished":"2014-12-30T12:33:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/"},"wordCount":301,"publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png","articleSection":["Mode"],"inLanguage":"fr-FR","copyrightYear":"2014","copyrightHolder":{"@id":"https:\/\/www.retaildetail.be\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/","url":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/","name":"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30% - RetailDetail BE","isPartOf":{"@id":"https:\/\/www.retaildetail.be\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#primaryimage"},"image":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#primaryimage"},"thumbnailUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png","datePublished":"2014-12-30T12:33:19+00:00","breadcrumb":{"@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#primaryimage","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png","width":281,"height":147},{"@type":"BreadcrumbList","@id":"https:\/\/www.retaildetail.be\/fr\/news\/mode\/la-moitie-des-boutiques-demarrent-les-soldes-avec-des-reductions-de-30\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.retaildetail.be\/fr\/"},{"@type":"ListItem","position":2,"name":"La moiti\u00e9 des boutiques d\u00e9marrent les soldes avec des r\u00e9ductions de 30%"}]},{"@type":"WebSite","@id":"https:\/\/www.retaildetail.be\/nl\/#website","url":"https:\/\/www.retaildetail.be\/nl\/","name":"RetailDetail BE","description":"News","publisher":{"@id":"https:\/\/www.retaildetail.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.retaildetail.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.retaildetail.be\/nl\/#organization","name":"RetailDetail BE","url":"https:\/\/www.retaildetail.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","contentUrl":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.svg","width":131,"height":70,"caption":"RetailDetail BE"},"image":{"@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.retaildetail.be\/nl\/#\/schema\/person\/ba2d383452a753a3a1ce8cdb349b5fc9","name":"dev@grandiz.com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5f53ce9fb6eed4a60e5aaaa712be8773880fa9459d9cac9bc4aa4fdbce3f447f?s=96&d=mm&r=g","caption":"dev@grandiz.com"},"sameAs":["http:\/\/preprod.retaildetail.be"],"url":"https:\/\/www.retaildetail.be\/fr\/author\/devgrandiz-com\/"}]}},"jetpack_featured_media_url":"https:\/\/www.retaildetail.be\/wp-content\/uploads\/2022\/04\/logo.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/7835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/comments?post=7835"}],"version-history":[{"count":0,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/posts\/7835\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media\/84"}],"wp:attachment":[{"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/media?parent=7835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/categories?post=7835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/tags?post=7835"},{"taxonomy":"people","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/people?post=7835"},{"taxonomy":"extra","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/extra?post=7835"},{"taxonomy":"company","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/company?post=7835"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/topic?post=7835"},{"taxonomy":"region","embeddable":true,"href":"https:\/\/www.retaildetail.be\/fr\/wp-json\/wp\/v2\/region?post=7835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}